{"id":360,"count":3,"description":"","link":"https:\/\/clinicdermatech.com\/blog\/tag\/facelift-procedure\/","name":"Facelift Procedure","slug":"facelift-procedure","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/clinicdermatech.com\/blog\/wp-json\/wp\/v2\/tags\/360"}],"collection":[{"href":"https:\/\/clinicdermatech.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/clinicdermatech.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/clinicdermatech.com\/blog\/wp-json\/wp\/v2\/posts?tags=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}